{"id":61,"date":"2021-04-30T12:42:01","date_gmt":"2021-04-30T12:42:01","guid":{"rendered":"http:\/\/espanoleschool.com\/escuela\/?page_id=61"},"modified":"2025-01-31T09:00:47","modified_gmt":"2025-01-31T08:00:47","slug":"la-escuela","status":"publish","type":"page","link":"https:\/\/espanoleschool.com\/es\/international-house-valencia\/la-escuela\/","title":{"rendered":"Una escuela muy especial"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;cabecera-curso&#8221;][vc_column][vc_column_text]\n\n<div class=\"mybreadcrumb\"> \n    <a href=\"\/\">HOME<\/a> >  La escuela<\/div>\n<h1>Muralla, palacio y escuela de espa\u00f1ol en Valencia. <span style=\"text-decoration: underline;\">Bienvenidos a Espa\u00f1ol\u00e9.<\/span><\/h1>\n<p>Alojada en un antiguo palacio completamente restaurado, nuestra academia de espa\u00f1ol en Valencia, Espa\u00f1ol\u00e9, conserva el encanto de su pasado hist\u00f3rico en unas modernas instalaciones completamente equipadas para que disfrutes de cada momento con nosotros.[\/vc_column_text][vc_raw_html]JTNDbGluayUyMHJlbCUzRCUyMnN0eWxlc2hlZXQlMjIlMjBocmVmJTNEJTIyaHR0cHMlM0ElMkYlMkZ1bnBrZy5jb20lMkZzd2lwZXIlMkZzd2lwZXItYnVuZGxlLm1pbi5jc3MlMjIlMjAlMkYlM0UlMEE=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1634611923986{margin-bottom: 1em !important;}&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1637155932361{margin-top: 24px !important;}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">\u00a1Descubre la escuela!<\/h2>\n<p style=\"text-align: center;\">Acomp\u00e1\u00f1anos.<\/p>\n<p>[\/vc_column_text]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid fila-gallery\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-9615 gallery-columns-1 gallery-size-full'><div class=\"swiper-container mySwiper-gallery\">\n      <div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_6_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_6_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_6_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_6_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"920\" height=\"492\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_023DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_023DFR.jpg 920w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_023DFR-300x160.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_023DFR-768x411.jpg 768w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases38_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases38_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases38_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases38_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_12_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_12_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_12_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_12_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_4_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_4_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_4_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_4_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_11_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_11_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_11_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_11_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"920\" height=\"483\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_062DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_062DFR.jpg 920w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_062DFR-300x158.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_062DFR-768x403.jpg 768w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_24_1_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_24_1_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_24_1_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_24_1_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"915\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_136DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_136DFR.jpg 915w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_136DFR-300x157.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_136DFR-768x403.jpg 768w\" sizes=\"(max-width: 915px) 100vw, 915px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_31_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_31_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_31_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_31_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_15_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_15_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_15_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_15_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"920\" height=\"481\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_055DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_055DFR.jpg 920w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_055DFR-300x157.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_055DFR-768x402.jpg 768w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"914\" height=\"483\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_042DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_042DFR.jpg 914w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_042DFR-300x159.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_042DFR-768x406.jpg 768w\" sizes=\"(max-width: 914px) 100vw, 914px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"918\" height=\"482\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_088DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_088DFR.jpg 918w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_088DFR-300x158.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_088DFR-768x403.jpg 768w\" sizes=\"(max-width: 918px) 100vw, 918px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_9_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_9_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_9_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_9_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_7_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_7_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_7_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_7_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_5_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_5_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_5_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_5_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_30_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_30_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_30_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_30_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"918\" height=\"482\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_043DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" aria-describedby=\"gallery-1-8027\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_043DFR.jpg 918w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_043DFR-300x158.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_043DFR-768x403.jpg 768w\" sizes=\"(max-width: 918px) 100vw, 918px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_21_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_21_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_21_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_21_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_2_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_2_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_2_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_2_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_8_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_8_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_8_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_8_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_18_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_18_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_18_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_18_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_29_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_29_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_29_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_29_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"920\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_112DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_112DFR.jpg 920w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_112DFR-300x157.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_112DFR-768x401.jpg 768w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases23_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases23_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases23_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases23_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_22_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_22_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_22_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_22_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_20_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_20_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_20_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_20_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"912\" height=\"482\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_053DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_053DFR.jpg 912w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_053DFR-300x159.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_053DFR-768x406.jpg 768w\" sizes=\"(max-width: 912px) 100vw, 912px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_25_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_25_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_25_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_25_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_28_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_28_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_28_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_28_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases6_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases6_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases6_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases6_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases24_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases24_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases24_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases24_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_16_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_16_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_16_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_16_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"915\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_103DFR.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_103DFR.jpg 915w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_103DFR-300x157.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/13418_103DFR-768x403.jpg 768w\" sizes=\"(max-width: 915px) 100vw, 915px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_3_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_3_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_3_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_3_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases17_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases17_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases17_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/06\/Clases17_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"921\" height=\"480\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_17_921x480.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_17_921x480.jpg 921w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_17_921x480-300x156.jpg 300w, https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/11\/Escuela_2021_17_921x480-768x400.jpg 768w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/div><\/div><div class=\"swiper-button-prev\"><\/div>\n            <div class=\"swiper-button-next\"><\/div><\/div><\/div>\n <!-- Swiper JS -->\n    <script src=\"https:\/\/unpkg.com\/swiper\/swiper-bundle.min.js\"><\/script>\n\n    <!-- Initialize Swiper -->\n    <script>\n      var swiper = new Swiper(\".mySwiper-gallery\", {\n        slidesPerView: 1.5,\n        loop:true,\n        lazy: true,\n        centeredSlides: true,\n        spaceBetween: 10,\n        slideActiveClass:\"swiper-slide-active\",\n        \/\/ Navigation arrows\n        navigation: {\n            nextEl: \".swiper-button-next\",\n            prevEl: \".swiper-button-prev\",\n        },\n      });\n    <\/script>\n\t\n<div class=\"mceTemp\"><\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221;][vc_column][vc_column_text][\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3>Muralla<\/h3>\n<p>El interior de Espa\u00f1ol\u00e9 alberga algunos de los restos mejor conservados de la antigua muralla \u00e1rabe que rodeaba la ciudad en el s.XI: parte de la Puerta de la Culebra, que se cre\u00eda desaparecida, fue recuperada e integrada en el edificio junto con arcos y fragmentos del lienzo defensivo.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3 style=\"text-align: left;\">Palacio<\/h3>\n<p style=\"text-align: left;\">Nuestra escuela fue en su origen un palacio g\u00f3tico de finales del siglo XIII, que con el paso de los a\u00f1os ha experimentado sucesivas remodelaciones y reformas hasta su estado actual. A\u00fan podemos disfrutar del patio central, de los arcos y escaleras y en la zona de oficina, de un artesonado bellamente policromado de mas de 7 siglos de antig\u00fcedad.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3>Escuela<\/h3>\n<p>Hoy, nuestros estudiantes conviven en Espa\u00f1ol\u00e9 con fragmentos de la historia de Valencia y disfrutan de un espacio singular donde se comparten risas, ilusi\u00f3n y ganas de aprender. Nuestra escuela es un lugar de encuentro entre diferentes culturas y un espacio de acogida que nuestros alumnos sienten como propio.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Nuestras instalaciones<\/h2>\n<p style=\"text-align: center;\">Los antiguos restos de la muralla \u00e1rabe atraviesan la escuela y conviven con las aulas y con nuevos espacios especialmente dise\u00f1ados conforme a nuestra visi\u00f3n de c\u00f3mo deber\u00eda ser una escuela de idiomas en el siglo XXI: una combinaci\u00f3n de historia y modernidad .<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;seccion-textos-fotos-cols&#8221; css=&#8221;.vc_custom_1634612037041{margin-bottom: -2.5em !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"titulo\">Las aulas<\/h3>\n<p>Pensadas para que aproveches al m\u00e1ximo tus clases, nuestras aulas est\u00e1n completamente equipadas con todo lo necesario para tu aprendizaje. Son amplias y luminosas para que cada estudiante disponga de un espacio c\u00f3modo de trabajo.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;980&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;seccion-textos-fotos-cols reverse&#8221; css=&#8221;.vc_custom_1634612043516{margin-bottom: -2.5em !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10409&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"titulo\">Patios y terrazas<\/h3>\n<p>Para disfrutar del sol, para descansar entre clase y clase o para reunirte con otros estudiantes&#8230;los patios y terrazas son espacios de recreo preparados para los momentos de relax y diversi\u00f3n.[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;seccion-textos-fotos-cols&#8221; css=&#8221;.vc_custom_1634612050572{margin-bottom: -2.5em !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"titulo\">Espacio para estudiantes<\/h3>\n<p>Tienes a tu disposici\u00f3n salas y espacios comunes alrededor de los cuales se desarrolla la vida de la escuela. Aprovecha cada momento para compartir experiencias y practicar tu espa\u00f1ol con otros estudiantes como t\u00fa.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10400&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;seccion-textos-fotos-cols reverse&#8221; css=&#8221;.vc_custom_1634612007865{margin-bottom: -1em !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10392&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"titulo\">Zonas de trabajo y acogida al estudiante<\/h3>\n<p>Para ayudarte en lo que necesites, cuentas con un equipo de profesionales que te acompa\u00f1ar\u00e1n durante tu estancia con nosotros. Encu\u00e9ntranos en las zonas de trabajo, donde atenderemos tus dudas y consultas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row gap=&#8221;30&#8243; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; disable_element=&#8221;yes&#8221; el_class=&#8221;seccion-textos-fotos-cols reverse&#8221; css=&#8221;.vc_custom_1738310441989{margin-bottom: -1em !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"titulo\">Restaurante de la escuela<\/h3>\n<p>En &#8220;La Mala&#8221;, restaurante de la escuela, podr\u00e1s reunirte con tus compa\u00f1eros, socializar y disfrutar de nuestra deliciosa gastronom\u00eda junto a otros estudiantes. &#8220;La Mala&#8221; ofrece un ambiente c\u00f3modo y acogedor donde podr\u00e1s relajarte y descansar, durante tus pausas. No solo es un lugar para ir a comer o tomar un caf\u00e9, sino que tambi\u00e9n fomenta las relaciones entre nuestros alumnos.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;48729&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">\u00bfTe apetece dar una vuelta por la escuela?<\/h2>\n<p style=\"text-align: center;\">Recorre el tour virtual.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYwOTUzNjUyOTc5JTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRTl4WkdkbVVXVnBkQzB6YTJ0S2VUZ3pVbkpCUlVKc1NWWTRXVmMzU2poWVMzQlJaekpGJTIxMm0yJTIxMWQzOS40NzY1MDg0NDU1MzIlMjEyZC0wLjM3OTU5Nzk5NjU5MDUyJTIxM2YyLjQ0OTU4NjIzNzU3NTc2OTglMjE0ZjE1LjU1OTQ4NTI3ODY3MTQzMSUyMTVmMC43ODIwODY1OTc0NjI3NDY5JTIyJTIwd2lkdGglM0QlMjIxMDAlMjUlMjIlMjBoZWlnaHQlM0QlMjI0NTAlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQSUyMDAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjJ0cnVlJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYxMDIyNTkyNjg2JTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRkF3TW5KWVVXeDBTRzA1WDBoUWRubDBWV0ZpY2pseFRFSmxNV1JHVWxwU04yNW9jbEZmJTIxMm0yJTIxMWQzOS40NzY1NzczMTMyMzclMjEyZC0wLjM3OTU5MTU5MzM3MzIyJTIxM2YyNzMuNDIzMTQzMzQ3MDAzNTMlMjE0ZjUuMDg0MzMwNzY5NTcwNTQyJTIxNWYwLjc4MjA4NjU5NzQ2Mjc0NjklMjIlMjB3aWR0aCUzRCUyMjEwMCUyNSUyMiUyMGhlaWdodCUzRCUyMjMwMCUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMHN0eWxlJTNEJTIyYm9yZGVyJTNBJTIwMCUzQiUyMiUyMGFsbG93ZnVsbHNjcmVlbiUzRCUyMnRydWUlMjIlM0UlM0MlMkZpZnJhbWUlM0U=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYxMDIzOTMwMjAwJTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRkE0VUhCcmVrWjNRWEJZYXpoak5VaG1WVFZyZVRCelNsRnhabkpQYjBWcmRXbFdWSEZGJTIxMm0yJTIxMWQzOS40NzY2MTcxNjUxMzIlMjEyZC0wLjM3OTU4MTQwNDM3MTA0JTIxM2YzNTQuMzMzODIxNTk2MDc2ODYlMjE0ZjExLjcyNjgwMDAxMzYyNTQ3OCUyMTVmMC43ODIwODY1OTc0NjI3NDY5JTIyJTIwd2lkdGglM0QlMjIxMDAlMjUlMjIlMjBoZWlnaHQlM0QlMjIzMDAlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQSUyMDAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjJ0cnVlJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>El Tossal<\/h3>\n<p>Nuestra \u00e1rea exclusiva para que los estudiantes se relajen, estudien y socialicen. Este es tambi\u00e9n la zona del departamento de actividades donde pueden inscribirse a las actividades y excursiones programadas.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>El claustro<\/h3>\n<p>La plaza central de la escuela donde se puede acceder a todas las partes del complejo as\u00ed como a la Recepci\u00f3n y al Departamento Acad\u00e9mico.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYxMDI0Mjk1MDg5JTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRTVzVVdaU1ZtdGFaRjlCVlRsaGNIVm5OMlJsVDFSMlZGbGxjWGs0ZVZrMlZFbzBUakZ5JTIxMm0yJTIxMWQzOS40NzY2MjY2Mjc0MjElMjEyZC0wLjM3OTUzNTEyNTIzNjA5JTIxM2YzMi4wMzIwODg3OTg4NDE0ODUlMjE0Zi0zLjQ2MDQ0Nzk4MTE2Nzg3NDMlMjE1ZjAuNzgyMDg2NTk3NDYyNzQ2OSUyMiUyMHdpZHRoJTNEJTIyMTAwJTI1JTIyJTIwaGVpZ2h0JTNEJTIyMzAwJTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTIwc3R5bGUlM0QlMjJib3JkZXIlM0ElMjAwJTNCJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNEJTIydHJ1ZSUyMiUzRSUzQyUyRmlmcmFtZSUzRQ==[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYxMDI0NDgzODQyJTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRTV4YldGbk5DMHRUbEpqVmxoRlVIWlNja2t6UlRoaVJYZFNXRXh0VFRKWmEydHJZV04wJTIxMm0yJTIxMWQzOS40NzY4ODg0MzUwNCUyMTJkLTAuMzc5NDUzNzQxNzE0ODglMjEzZjI0NC41OTI5Njc0NjUzNzg3MyUyMTRmNi43MjQ3OTg0NDY4ODU3OTklMjE1ZjAuNzgyMDg2NTk3NDYyNzQ2OSUyMiUyMHdpZHRoJTNEJTIyMTAwJTI1JTIyJTIwaGVpZ2h0JTNEJTIyMzAwJTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTIwc3R5bGUlM0QlMjJib3JkZXIlM0ElMjAwJTNCJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNEJTIydHJ1ZSUyMiUzRSUzQyUyRmlmcmFtZSUzRQ==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>Hannax<\/h3>\n<p>\u00a1Es la parte m\u00e1s antigua de la escuela que a\u00fan conserva las murallas originales de la ciudad y una torre del siglo XI junto a las aulas! Caminar\u00e1s por la calle por la que caminaron nuestros antepasados \u200b\u200bvalencianos hace casi 1000 a\u00f1os.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>El patio<\/h3>\n<p>Adem\u00e1s de las aulas, nuestros estudiantes tambi\u00e9n utilizan el Patio en sus descansos y despu\u00e9s de clases. En esta \u00e1rea tambi\u00e9n organizamos nuestras fiestas, barbacoas y cocinamos paellas. Aqu\u00ed tambi\u00e9n se encuentra el aula de cocina donde te ense\u00f1amos a hacer muchas otras delicias espa\u00f1olas.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxNHYxNTYxMDI0Nzg2ODY0JTIxNm04JTIxMW03JTIxMXNDQW9TTEVGR01WRnBjRTl0VWtWRVoyeFdhVGRPWm01dk16SnFhbWt6ZVdaWVFXUnVOa3QyU0haVldUWnhNRFpMJTIxMm0yJTIxMWQzOS40NzY1OTQzMjY5MyUyMTJkLTAuMzc5NTU5MDYxMDAyOTYlMjEzZjEzMS41NTAzMTcyMzMxMzIxNSUyMTRmMC4xNDQ0NTY2MzY2NDY5MjE3NyUyMTVmMC43ODIwODY1OTc0NjI3NDY5JTIyJTIwd2lkdGglM0QlMjIxMDAlMjUlMjIlMjBoZWlnaHQlM0QlMjIzMDAlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQSUyMDAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjJ0cnVlJTIyJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>La muralla<\/h3>\n<p><strong><br \/>\n<\/strong>La parte m\u00e1s nueva del edificio tambi\u00e9n se puede describir como la m\u00e1s impresionante visualmente. Aqu\u00ed est\u00e1n perfectamente combinados la historia y el dise\u00f1o moderno, tenemos muchas aulas espectaculares para que disfrutes. En esta zona tambi\u00e9n tenemos una gran terraza donde puedes descansar e incluso puedes tomar el sol.[\/vc_column_text][\/vc_column][\/vc_row][vc_row content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h2>En el centro de Valencia<\/h2>\n<p>En el mismo coraz\u00f3n de Valencia, junto al famoso Mercado Central, rodeada de historia y cultura. Muy cerca de la zona comercial y ubicada en un espacio lleno de vida y actividad, nuestra escuela disfruta de una ubicaci\u00f3n privilegiada.<\/p>\n<p><a class=\"botones bot-azul\" href=\"https:\/\/espanoleschool.com\/contact-us\/\">Contacta con nosotros<\/a>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_gmaps link=&#8221;#E-8_JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xOCUyMTFtMTIlMjExbTMlMjExZDMwNzkuNjgxNzgxOTkzMDAyNSUyMTJkLTAuMzgxNzUxMDQ5MjIyNTk5MiUyMTNkMzkuNDc2NTE3MTIwMTAzOTg1JTIxMm0zJTIxMWYwJTIxMmYwJTIxM2YwJTIxM20yJTIxMWkxMDI0JTIxMmk3NjglMjE0ZjEzLjElMjEzbTMlMjExbTIlMjExczB4ZDYwNDhiNWFhYjljZmEzJTI1M0EweGVmOTM2MDYxYjk0MTA4NCUyMTJzRXNwYSUyNUMzJTI1QjFvbCUyNUMzJTI1QTklMjUyMEloJTI1MjBWYWxlbmNpYS0lMjUyMFNwYW5pc2glMjUyMFNjaG9vbCUyMTVlMCUyMTNtMiUyMTFzZW4lMjEyc2VzJTIxNHYxNjMwOTAyMzA5NzcyJTIxNW0yJTIxMXNlbiUyMTJzZXMlMjIlMjB3aWR0aCUzRCUyMjYwMCUyMiUyMGhlaWdodCUzRCUyMjQ1MCUyMiUyMGZyYW1lYm9yZGVyJTNEJTIyMCUyMiUyMHN0eWxlJTNEJTIyYm9yZGVyJTNBMCUyMiUyMGFsbG93ZnVsbHNjcmVlbiUzRSUzQyUyRmlmcmFtZSUzRQ==&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">\u00a1S\u00edguenos!<\/h2>\n<p style=\"text-align: center;\">S\u00edguenos en nuestras redes sociales para estar al tanto de las \u00faltimas noticias de tu escuela de espa\u00f1ol en Valencia de confianza, Espa\u00f1ol\u00e9.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1630927416777{background-color: #f0faff !important;}&#8221;][vc_column]<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><strong><span style=\"color: #3a9bde; font-size: 2em;\">\u00bfEn qu\u00e9 podemos ayudarte?<\/span><\/strong><\/p>\n<p style=\"text-align: center;\">Contacta con nosotros, estamos encantados de ayudarte.<\/p>\n<div class=\"templatera_shortcode\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js-eu1.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    portalId: \"144814303\",\n    formId: \"0bc3daaa-8ee6-4fdb-b880-c120b48929b4\"\n  });\n<\/script>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;seccion-faq&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Preguntas frecuentes<\/h2>\n<p>[vc_toggle title=&#8221;#1 \u00bfC\u00f3mo es la escuela?&#8221;]Espanol\u00e9 est\u00e1 situada en un palacio g\u00f3tico en el centro de la ciudad, ofrece excelentes instalaciones para el estudio de idiomas. Cuenta con 28 espaciosas aulas con aire acondicionado, luz natural y pizarras interactivas, zona de estudiantes, un gran patio y dos terrazas.[\/vc_toggle][vc_toggle title=&#8221;#2 \u00bfD\u00f3nde est\u00e1 la escuela?&#8221;]Espa\u00f1ol\u00e9 est\u00e1 justo en el centro, en una de las calles m\u00e1s tradicionales de la ciudad, junto a la antigua Universidad de Valencia, a 2 minutos andando de la Catedral, Ayuntamiento&#8230; y de todos los sitios de inter\u00e9s. Se encuentra entre la parte hist\u00f3rica y la zona comercial[\/vc_toggle][vc_toggle title=&#8221;#3 \u00bfA qu\u00e9 distancia se encuentra la playa de la escuela?&#8221;]La playa est\u00e1 a unos 20 minutos en autob\u00fas de la escuela.[\/vc_toggle][vc_toggle title=&#8221;#4 \u00bfCu\u00e1l es el promedio de edad y nacionalidad de los estudiantes?&#8221;]La mayor\u00eda de los estudiantes tiene entre 18 y 60 a\u00f1os. La nacionalidad de los alumnos depende de la \u00e9poca del a\u00f1o. Nuestros estudiantes provienen de muchos pa\u00edses diferentes y es nuestro objetivo mantener una mezcla alta de nacionalidades.[\/vc_toggle][vc_toggle title=&#8221;#5 \u00bfCu\u00e1ntos alumnos hay por clase?&#8221;]<span class=\"hps\">Los grupos son<\/span>\u00a0<span class=\"hps\">de<\/span>\u00a0<span class=\"hps\">m\u00e1ximo<\/span>\u00a0<span class=\"hps\">10<\/span>\u00a0<span class=\"hps\">estudiantes.<\/span>\u00a0<span class=\"hps\">En algunos cursos<\/span>\u00a0<span class=\"hps\">especiales<\/span>\u00a0<span class=\"hps\">y de preparaci\u00f3n<\/span>\u00a0<span class=\"hps\">para ex\u00e1menes puede haber entre 4 a 6 alumnos por clase.<\/span>[\/vc_toggle][vc_toggle title=&#8221;#6 \u00bfCu\u00e1ntos estudiantes hay en la escuela?&#8221;] Invierno: 180, Primavera \/ Oto\u00f1o: 250, Verano: 350[\/vc_toggle][vc_toggle title=&#8221;#7 \u00bfInternet?&#8221;]En la escuela hay WIFI gratuito as\u00ed como ordenadores de uso libre con conexi\u00f3n a internet a disposici\u00f3n de los estudiantes.[\/vc_toggle][vc_toggle title=&#8221;#8 \u00bfPuedo practicar deportes?&#8221;]Valencia te ofrece muchas oportunidades para practicar tus deportes favoritos. Cerca de la escuela hay instalaciones deportivas donde puedes jugar al tenis, al baloncesto, al f\u00fatbol, al squash o hacer ejercicios aer\u00f3bicos y gimnasio.[\/vc_toggle][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">Un enseignement de la plus haute qualit\u00e9<\/h2>\n<p style=\"text-align: center;\">Les certifications et les labels de qualit\u00e9 les plus importants garantissent l&#8217;excellence de notre \u00e9cole.<\/p>\n<p>[\/vc_column_text][vc_column_text]\t<div class=\"swiper-container swiper-certifications\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/portail.chorus-pro.gouv.fr\/aife_csm\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2025\/09\/ChorusPro.png\" alt=\"Chorus Pro\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/ihworld.com\/ih-valencia-ih-quality-inspection-digital-badge\/\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2025\/09\/IH-Quality-Inspeciton-badge-2024-2027-1.png\" alt=\"IH Valencia \u2013 IH Quality Inspection Digital Badge\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/www.visitvalencia.com\/\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2023\/11\/Empresa-Asociada-Fundacio-VISIT-VLC.png\" alt=\"Visit Val\u00e8ncia\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/espanoleschool.com\/es\/proyecto\/\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2022\/11\/colaboracio2025.png\" alt=\"Comunitat Valenciana &#8211; Mediterr\u00e1neo en vivo y seguro\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/www.comunitatvalenciana.com\/en\/be-inspired\/language-travel\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2022\/02\/learning_spanish-comunitat-valenciana.jpg\" alt=\"Comunitat Valenciana\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/bildungsurlaub-approval.de\/#\/\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/07\/Picture-1.png\" alt=\"BILDUNGSURLAUB\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/07\/Picture-2.png\" alt=\"CSN\">\n\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/07\/Picture-3.png\" alt=\"Certificado ISO-14064\">\n\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/acreditacion.cervantes.es\/centros_espana.htm#castellon\" rel=\"noopener\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/07\/Picture-4.png\" alt=\"Centro Acreditado: Instituto Cervantes\">\n<\/a>\t\t\t<\/div>\n\t\t\t<div class=\"swiper-slide\">\n<a target=\"_blank\" href=\"https:\/\/espanoleschool.com\/es\/proyecto-subvencionado-por-ivace-y-la-ue\/\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2025\/06\/IVACE.png\" alt=\"Proyecto subvencionado por IVACE y la Uni\u00f3n Europea\">\n<\/a>\t\t\t<\/div>\n\t<\/div>\n\t<div class=\"swiper-button-prev\"><\/div>\n\t<div class=\"swiper-button-next\"><\/div>\n\t<\/div>\n<script src=\"https:\/\/espanoleschool.com\/escuela\/wp-content\/plugins\/CPT_Cursos\/js\/swiper-bundle.js\"><\/script>\n<link rel=\"stylesheet\" href=\"https:\/\/unpkg.com\/swiper\/swiper-bundle.min.css\" \/>\n    <script>\n      var swiper_certs = new Swiper(\".swiper-certifications\", {\n        direction: 'horizontal',\n        loop: true,\n        slidesPerView: 5,\n        spaceBetween: 0,\n        centeredSlides: true,\n        pagination: {\n            el: \".swiper-pagination\",\n            clickable: true,\n        },\n        \/\/ Navigation arrows\n        navigation: {\n            nextEl: '.swiper-button-next',\n            prevEl: '.swiper-button-prev',\n        },\n    });\n    <\/script>\n\n[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":65,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","rank_math_lock_modified_date":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-61","page","type-page","status-publish","entry"],"rankMath":{"parentDomain":"espanoleschool.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"La imagen destacada debe tener al menos 200 por 200 p\u00edxeles para que Facebook y otros sitios de redes sociales puedan escogerla.","pluginReviewed":false,"postSettings":{"linkSuggestions":false,"useFocusKeyword":false},"frontEndScore":false,"postName":"spanish-in-spain","permalinkFormat":"https:\/\/espanoleschool.com\/es\/?certificacion=spanish-in-spain\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/espanoleschool.com\/escuela\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"Javier Peinado","primaryTerm":0,"authorName":"Cristina","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/espanoleschool.com\/es\/","objectID":42169,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Icono de reproducci\u00f3n","url":"https:\/\/espanoleschool.com\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/espanoleschool.com\/public_html\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icono GIF","url":"https:\/\/espanoleschool.com\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/espanoleschool.com\/public_html\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/espanoleschool.com\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fespanoleschool.com%2Fes%2F&r=https%3A%2F%2Fespanoleschool.com%2Fes%2Fwp-json%2Fwp%2Fv2%2Fpages%2F61%2F%3Fnonce%3D339f07399c","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/espanoleschool.com\/escuela\/wp-content\/uploads\/2021\/04\/cropped-Logo-Espanole-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Actualizar","trendsPreviewImage":"https:\/\/espanoleschool.com\/escuela\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/pages\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":9,"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":54897,"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/pages\/61\/revisions\/54897"}],"up":[{"embeddable":true,"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/pages\/65"}],"wp:attachment":[{"href":"https:\/\/espanoleschool.com\/es\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}